{"id":19606,"date":"2024-10-17T10:23:01","date_gmt":"2024-10-17T16:23:01","guid":{"rendered":"https:\/\/www.iccu.com\/blog\/sin-categorizar\/los-abcd-de-medicare-con-el-agente-de-seguros-corban-latimore\/"},"modified":"2025-04-16T12:37:45","modified_gmt":"2025-04-16T18:37:45","slug":"the-abcds-of-medicare-with-insurance-agent-corban-latimore","status":"publish","type":"post","link":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/","title":{"rendered":"Los ABCD de Medicare con el agente de seguros Corban Latimore"},"content":{"rendered":"\n<p>Aprender los entresijos de Medicare puede parecerse mucho a aprender una lengua extranjera. Al principio puede parecer un galimat\u00edas complicado, pero a medida que te sumerjas en sus complejidades, con el tiempo cosechar\u00e1s los frutos. <\/p>\n\n<p>El problema, por desgracia, es precisamente \u00e9se: el tiempo. Muchos de nosotros apenas tenemos tiempo para gestionar nuestra vida cotidiana, y mucho menos para abordar el lenguaje de Medicare. <\/p>\n\n<p>Por eso hemos recurrido a la ayuda de uno de nuestros expertos en seguros, Corban Latimore.* <strong>Mira el podcast o lee la transcripci\u00f3n a continuaci\u00f3n para aprender las distintas partes de Medicare, las fechas importantes a las que debes estar atento y mucho m\u00e1s, en menos de 15 minutos.<\/strong><\/p>\n\n<figure class=\"wp-block-embed is-type-video is-provider-youtube wp-block-embed-youtube wp-embed-aspect-16-9 wp-has-aspect-ratio\"><div class=\"wp-block-embed__wrapper\">\n<iframe loading=\"lazy\" title=\"Idaho Central Credit Union Insurance Services\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/pB5s8ohaVM4?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe>\n<\/div><\/figure>\n\n<p class=\"has-md-font-size\"><em><strong>Nota: Este art\u00edculo y el podcast s\u00f3lo pretenden ofrecer informaci\u00f3n general. Para discutir tu situaci\u00f3n espec\u00edfica, habla con un profesional cualificado. <\/strong><\/em><\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-medicare-s-key-enrollment-dates\">\u00bfCu\u00e1les son las fechas clave de inscripci\u00f3n en Medicare?<\/h2>\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Periodo de inscripci\u00f3n inicial (PEI):<\/mark> Var\u00eda en funci\u00f3n de la fecha de nacimiento<\/strong>. Lo m\u00e1s habitual es que la afiliaci\u00f3n inicial comience tres meses antes de cumplir los <sup>65<\/sup> a\u00f1os y finalice tres meses despu\u00e9s. <\/p>\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Periodo de Afiliaci\u00f3n Anual (AEP):<\/mark> Del 15 de Octubre al 7 de Diciembre.<\/strong> Es una oportunidad para cambiar de plan o de proveedor de Medicare, independientemente del plan de Medicare que tengas actualmente.<\/p>\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Periodo de inscripci\u00f3n abierta: <\/mark>Del 1 de Enero al 31 de Marzo<\/strong>. S\u00f3lo est\u00e1 abierto si quieres darte de baja de un plan Medicare Advantage y volver a un plan b\u00e1sico de Medicare. <\/p>\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Periodo de inscripci\u00f3n general:<\/mark> Del 1 de Enero al 31 de Marzo. <\/strong>Si no te inscribiste en el IEP al envejecer en Medicare, puedes hacerlo durante este periodo. <em>Si quieres inscribirte en un plan Medicare Advantage o de medicamentos, tendr\u00e1s que esperar hasta el 1 de abril &#8211; 30 de junio.<\/em><\/p>\n\n<p><strong><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Periodo de inscripci\u00f3n especial:<\/mark> Depende de los requisitos. <\/strong>Ponte en contacto con un <a href=\"https:\/\/www.iccu.com\/es\/insurance\/contact\/\">agente de seguros de ICCU<\/a> para ver si cumples los requisitos.<\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-what-are-medicare-parts-a-b-c-and-d\">\u00bfQu\u00e9 son las Partes A, B, C y D de Medicare?<\/h2>\n\n<p><strong>Parte A: <\/strong>Cubre los cuidados hospitalarios, los cuidados en centros de enfermer\u00eda especializada, los cuidados en residencias de ancianos, los cuidados paliativos y los servicios sanitarios a domicilio. Si trabajaste m\u00e1s de 10 a\u00f1os antes de inscribirte, es probable que ya hayas pagado tu parte de la prima a trav\u00e9s de tus n\u00f3minas. <\/p>\n\n<p><strong>Parte B: <\/strong>Cubre los servicios ambulatorios (visitas al m\u00e9dico), los servicios preventivos, las visitas anuales de bienestar, el transporte en ambulancia y los servicios m\u00e9dicos duraderos. La Parte B requiere una prima, que fluct\u00faa de a\u00f1o en a\u00f1o y var\u00eda en funci\u00f3n del salario, los impuestos, etc. Si no te inscribes en la Parte B durante la inscripci\u00f3n inicial, puedes enfrentarte a una cuota por inscripci\u00f3n tard\u00eda.  <\/p>\n\n<p><strong>Parte C:<mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"> <\/mark><\/strong>Cubre los programas de acondicionamiento f\u00edsico de Medicare, el transporte m\u00e9dico no urgente, la cobertura dental y oftalmol\u00f3gica y, ocasionalmente, la cobertura de medicamentos con receta. La Parte C la proporcionan compa\u00f1\u00edas de seguros privadas que se asocian con instituciones como ICCU Insurance Services para presentarte opciones personalizadas. Generalmente, puedes elegir entre dos subopciones: Medicare Advantage y Medigap. La cobertura depende del condado.   <\/p>\n\n<p><strong>Parte D: <\/strong>Cubre los medicamentos con receta. Si no te inscribes en la Parte D durante la inscripci\u00f3n inicial, puedes enfrentarte a una tasa por inscripci\u00f3n tard\u00eda. <\/p>\n\n<h2 class=\"wp-block-heading\" id=\"h-how-much-medicare-coverage-do-you-need\">\u00bfCu\u00e1nta cobertura de Medicare necesitas?<\/h2>\n\n<p>Aunque ning\u00fan art\u00edculo o podcast puede darte toda la informaci\u00f3n que necesitas para decidir tu asistencia m\u00e9dica, estos puntos b\u00e1sicos deber\u00edan darte una hoja de ruta para encontrar una cobertura de calidad. Cada persona tiene necesidades y preferencias m\u00e9dicas diferentes, y dependiendo de su ubicaci\u00f3n, la mayor\u00eda de la gente tiene diferentes planes a su disposici\u00f3n. <\/p>\n\n<p>Para aprender m\u00e1s sobre la cobertura de Medicare que tienes a tu disposici\u00f3n, ponte en contacto con un agente de ICCU Insurance Services. Te explicar\u00e1n los detalles y te asesorar\u00e1n seg\u00fan tu situaci\u00f3n. <\/p>\n\n<div class=\"wp-block-buttons is-layout-flex wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.iccu.com\/es\/insurance\/contact\/#meet-the-team\">Ver Agentes de seguros<\/a><\/div>\n\n\n\n<div class=\"wp-block-button is-style-inverted\"><a class=\"wp-block-button__link wp-element-button\" href=\"https:\/\/www.iccu.com\/es\/insurance\/\">Buscar servicios de seguros<\/a><\/div>\n<\/div>\n\n<h2 class=\"wp-block-heading\" id=\"h-read-the-transcript\">Leer la transcripci\u00f3n<\/h2>\n\n<p class=\"has-md-font-size\"><em>ICCU Insurance Services es una filial de ICCU. Los productos y servicios de los que se habla en este v\u00eddeo son distintos de los que ofrece ICCU. <\/em><\/p>\n\n<p><strong>Laura: <\/strong>Hola y bienvenidos a Tu Balance Diario, el podcast en v\u00eddeo de ICCU en el que estamos aqu\u00ed para ofrecerte consejos y trucos que te ayuden en tu camino hacia el \u00e9xito financiero. Y hoy estamos aqu\u00ed para hablar de todo lo relacionado con los servicios de seguros. \u00bfC\u00f3mo est\u00e1s, Corban?  <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><strong>Corban: <\/strong>Estoy bien.<\/mark><\/p>\n\n<p><strong>Laura: <\/strong>De acuerdo. Esto es bastante guay porque, independientemente de la etapa de tu vida en la que te encuentres, tenemos algunos productos nuevos de los que queremos hablar. Bueno, no nuevos, quiero decir, sino algunos productos realmente geniales, productos de seguros en ICCU. Y t\u00fa eres el especialista, as\u00ed que vamos a profundizar en ello. En primer lugar, Corban Latimore, \u00bfcu\u00e1l es tu funci\u00f3n en ICCU y en nuestros servicios de seguros?    <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><strong>Corban: <\/strong>S\u00ed, actualmente soy agente de seguros de ICCU en ICCU Insurance Services, donde ayudamos con todo lo relacionado con Medicare y los seguros de vida.<\/mark><\/p>\n\n<p><strong>Laura:<\/strong> Genial, \u00bfy cu\u00e1nto tiempo llevas en ICCU?<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><strong>Corban<\/strong>: Llevo aqu\u00ed algo m\u00e1s de nueve a\u00f1os, y dentro de mi funci\u00f3n actual como agente de seguros, algo m\u00e1s de a\u00f1o y medio.<\/mark><\/p>\n\n<p><strong>Laura:<\/strong> Genial. Y estoy segura, estoy segura de que has aprendido mucho sobre ello. Y hoy vamos a intentar desglosarlo para la gente, porque a veces los servicios de seguros pueden ser complicados. Y tambi\u00e9n, especialmente las cosas de Medicare. Hay algunas, hay algunas fechas clave que queremos tratar durante este podcast para ayudar realmente a educar a nuestros afiliados.    <\/p>\n\n<p>Bien, hablemos primero del equipo de agentes de seguros que tenemos en ICCU. H\u00e1blame de ese equipo y de qu\u00e9 tipo de cosas cubren. <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><strong>Corban: <\/strong>S\u00ed, tenemos un equipo incre\u00edble. Tenemos seis personas en total en nuestro grupo. Tenemos a nuestro gerente, y tenemos agentes en el condado de Ada, en Twin Falls, en Pocatello. Y cubrimos todo tipo de zonas para abarcar todo Idaho que podamos. Estamos estudiando entrar tambi\u00e9n en el norte de Idaho. Pero, s\u00ed, nuestro, nuestro objetivo es Medicare y los seguros de vida. As\u00ed que hacemos todo lo posible por llegar a nuestros miembros que se acercan a los 65 a\u00f1os e incluso a los mayores de 65 a\u00f1os que est\u00e1n actualmente en Medicare o quieren jubilarse. Ese es nuestro principal objetivo, asegurarnos de que se ocupan de ellos y de que obtienen las respuestas a las preguntas que buscan.       <\/mark><\/p>\n\n<p><strong>Laura:<\/strong> S\u00ed, y cuando te pones en contacto con la gente, puedes profundizar en todas las opciones disponibles, \u00bfverdad? As\u00ed que hay, usamos muchos transportistas diferentes y cosas por el estilo tambi\u00e9n. \u00bfC\u00f3mo funciona eso? \u00bfC\u00f3mo lo individualizas?   <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\"><strong>Corban:<\/strong> S\u00ed, con los Servicios de Seguros de ICCU, intentamos tener contrato con tantas aseguradoras como podemos en todo Idaho, para poder ofrecer a nuestros miembros todas las opciones que tienen a su disposici\u00f3n, para no tener que obligarles a contratar un plan que no tiene sentido. Podemos ofrecerles opciones para que no se sientan presionados de ninguna manera y se sientan c\u00f3modos con nosotros porque les damos la mejor soluci\u00f3n posible. <\/mark><\/p>\n\n<p><strong>Laura:<\/strong> S\u00ed, y luego puedes investigar las primas y las franquicias y los copagos y todo ese tipo de cosas para asegurarte de que es algo que les conviene.<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Exacto. S\u00ed, intentamos que sea un enfoque m\u00e1s individualizado. Ya sabes, cada situaci\u00f3n es diferente para todo el mundo. As\u00ed que no es un plan \u00fanico para todas las zonas. Eso es lo que hacemos mejor, un enfoque m\u00e1s personalizado.   <\/mark><\/p>\n\n<p>S\u00ed. As\u00ed que hablando directamente con Medicare, creo que una de las cosas que, especialmente oportunas tambi\u00e9n en esta \u00e9poca del a\u00f1o, es que hay algunas fechas clave en las que queremos incidir. Supongo que la primera, y en realidad no tiene que ver con esta \u00e9poca del a\u00f1o, es la inscripci\u00f3n inicial. Tiene que ver con tu cumplea\u00f1os. \u00bfC\u00f3mo funciona? 65 a\u00f1os es la edad m\u00e1gica, \u00bfverdad? Es cuando empieza a funcionar Medicare.     <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed. S\u00ed, as\u00ed es el confuso mundo de Medicare. Hay todo tipo de fechas y periodos de inscripci\u00f3n diferentes para todo el mundo. Pero realmente el n\u00famero m\u00e1gico es 65. Es el m\u00e1s com\u00fan. Eso es lo que se conoce como periodo de inscripci\u00f3n inicial. As\u00ed que te dan un poco de margen para que trabajes cuando envejezcas en Medicare. Es decir, tres meses antes de cumplir los 65 y tres meses despu\u00e9s. B\u00e1sicamente, tienes un plazo de siete meses para inscribirte en las distintas partes de Medicare y en los planes Advantage o complementarios que puedan estar disponibles.       <\/mark><\/p>\n\n<p>As\u00ed que si te est\u00e1s acercando a tu 65 cumplea\u00f1os, llamar a nuestros servicios de seguros ser\u00eda lo mejor que puedes hacer, porque realmente puedes empezar a explorarlo desde el principio, averiguando cu\u00e1les son las mejores opciones, y vas a obtener la mejor, la mejor cobertura en ese momento, cuando empieces justo a los 65 a\u00f1os.<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Exacto. S\u00ed, as\u00ed que es mejor adelantarse. Hay gente que se pone en contacto con nosotros mucho antes de cumplir los 65, s\u00f3lo para adelantarse. Pero s\u00ed, cuando la gente se acerca a su ventana, la mayor\u00eda tiene una buena idea de d\u00f3nde est\u00e1n y, ya sabes, intentan no posponerlo y perder el tren. As\u00ed que, s\u00ed, cuanto antes se pongan en contacto, antes podremos adelantarnos y mostrarles los planes disponibles y asegurarnos de que todas las partes de Medicare est\u00e1n preparadas para ellos.   <\/mark><\/p>\n\n<p>De acuerdo. Y entonces, vale, aqu\u00ed est\u00e1n las fechas clave: Del 15 de Octubre al 7 de Diciembre. Dinos por qu\u00e9 esas fechas son tan importantes. Y creo que deber\u00edamos repetirlas: Del 15 de Octubre al 7 de Diciembre, \u00bfverdad?   <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Claro, s\u00ed. S\u00ed, esta es una gran, es la pr\u00f3xima gran ventana de inscripci\u00f3n para todos los que est\u00e1n en Medicare. El periodo de inscripci\u00f3n anual, que va del 15 de Octubre al 7 de Diciembre, es una gran ventana para que todo el mundo cambie de plan. No puedes cambiar de plan en cualquier momento del a\u00f1o, tienes que hacerlo dentro de este plazo. As\u00ed que si ha habido alg\u00fan cambio en tu plan actual, o si, por ejemplo, te han recetado una medicaci\u00f3n diferente a lo largo del a\u00f1o, y tu plan actual no la cubre, del 15 de Octubre al 7 de Diciembre es el momento de encontrar un plan que te cubra.    <\/mark><\/p>\n\n<p>S\u00ed, y eso es muy importante. Creo que si alguien ya tiene Medicare pero quiere explorar diferentes opciones o incluso diferentes proveedores, \u00bfverdad? Acude a nosotros y habla con nosotros probablemente antes de ese periodo de tiempo para que puedas hacer esos cambios durante esas fechas.  <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Exacto.<\/mark><\/p>\n\n<p>Y luego, \u00bfqu\u00e9 es, qu\u00e9 es lo otro cuando lo llamas inscripci\u00f3n abierta?<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">La inscripci\u00f3n abierta&#8230; esa es otra ventana. Esta fecha cae entre el 1 de Enero y el 31 de Marzo. Y normalmente es para cualquiera que est\u00e9 actualmente en un plan Medicare Advantage, lo que le da la opci\u00f3n de darse de baja y volver al Medicare original, o para cualquiera que se haya saltado el plazo de inscripci\u00f3n inicial. Tienen la oportunidad de elegir un nuevo plan entre el 1 de Enero y el 31 de Marzo, de modo que est\u00e9n cubiertos.   <\/mark><\/p>\n\n<p>Bien. Bien. Me encanta que est\u00e9 todo eso, y como has dicho, hay un mont\u00f3n de fechas clave ah\u00ed. Bien, vamos a completarlo una vez m\u00e1s. Afiliaci\u00f3n inicial, es decir, cuando cumples 65 a\u00f1os, tres meses antes, tres meses despu\u00e9s.    <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed.<\/mark><\/p>\n\n<p>De acuerdo. Inscripci\u00f3n anual, fechas entre &#8230; <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">15 de Octubre y 7 de Diciembre.<\/mark><\/p>\n\n<p>Vale, es como un concurso. Y luego la inscripci\u00f3n abierta es entre &#8230; <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">1 de Enero y 31 de Marzo.<\/mark><\/p>\n\n<p>Estupendo. De acuerdo. Hemos cubierto todas las fechas. Es importante que marqu\u00e9is vuestros calendarios cuando teng\u00e1is esa edad. Bien, otra cosa que quer\u00eda cubrir hoy es un breve resumen de los planes de Medicare. Porque o\u00edmos hablar de A, B, C y D, y si pudi\u00e9ramos desglosarlos individualmente, qu\u00e9 significa A, y luego repasar\u00edamos las letras.     <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed, es toda la lista del alfabeto. [S\u00ed, as\u00ed que se trata de resolverlo. As\u00ed que, s\u00ed, aqu\u00ed es donde la gente puede confundirse. Dentro de Medicare, tienes la Parte A, la Parte B, la Parte C y la Parte D. \u00c9sas son las cuatro grandes partes que debes tener en cuenta.  <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">As\u00ed pues, con la Parte A de Medicare, \u00e9sta es la m\u00e1s com\u00fan. Es tu cobertura hospitalaria. Y \u00e9sta es la que todo el mundo ha estado pagando. En cada n\u00f3mina que recibes, sale esa parte de Medicare que se destina a esta prima. As\u00ed pues, la regla general es que mientras hayas trabajado al menos 10 a\u00f1os o m\u00e1s, habr\u00e1s pagado tu parte a esta prima, de modo que cuando cumplas 65 a\u00f1os y tengas derecho a ella, ya no tendr\u00e1s que pagar una prima, tendr\u00e1s que pagar la Parte A.    <\/mark><\/p>\n\n<p>Eso est\u00e1 muy bien.<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Ahora bien, la Parte B es tu cobertura m\u00e9dica. Y la Parte B tiene una prima, por lo que mucha gente lo pasa por alto. As\u00ed que cuando te jubiles y est\u00e9s listo para inscribirte en Medicare, te inscribes en la Parte B, y esta prima fluct\u00faa de a\u00f1o en a\u00f1o. A partir de este a\u00f1o, es de $174. Y depende de cu\u00e1nto hayas ganado y cu\u00e1nto hayas declarado en impuestos, pero hay diferentes niveles, pero el m\u00e1s bajo es de 174.70, y el a\u00f1o que viene eso cambiar\u00e1.    <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Y luego, eso es el Medicare original. Es la Parte A y la Parte B. Eso es lo esencial. Ahora bien, donde ICCU entra en juego con ICCU Insurance Services es que estamos contratados con estas compa\u00f1\u00edas que llevan estos planes de la Parte C. La Parte C la hacen las compa\u00f1\u00edas de seguros privadas.   <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Y en realidad hay dos \u00e1mbitos dentro de la Parte C. Est\u00e1n los planes Medicare Advantage y los planes Suplementarios o Medigap. Y es uno u otro. No puedes tener ambos. As\u00ed que depende de cada situaci\u00f3n. No es, como he dicho, una talla \u00fanica. Depende de lo que a la gente le d\u00e9 m\u00e1s tranquilidad le va a dar la cobertura que considere adecuada a sus necesidades.     <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">En cuanto a los planes Medicare Advantage, se determinan por condado, de modo que seg\u00fan donde vivas, hay ciertos planes disponibles y otros que no lo est\u00e1n.<\/mark><\/p>\n\n<p>De acuerdo.<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Y ciertos planes cubrir\u00e1n las recetas y algunas cosas cubrir\u00e1n los copagos de forma diferente, as\u00ed que eso es lo que nos gusta diseccionar y asegurarnos de que la gente se est\u00e1 configurando correctamente.<\/mark><\/p>\n\n<p>\u00bfPuedo detenerte ah\u00ed? Porque tengo una pregunta. Cuando la gente, cuando llega el momento de esas conversaciones, \u00bflo mejor que puede hacer es ponerse en contacto contigo directamente, consultar nuestro sitio web, obtener nuestra informaci\u00f3n de contacto y ponerse en contacto contigo para poder tener esas conversaciones detalladas? Porque parece m\u00e1s complicado cuando entras en el \u00e1rea C y D, \u00bfverdad?   <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Absolutamente. S\u00ed, definitivamente es un mundo complejo. Y es algo que los agentes de todo el mundo tambi\u00e9n intentan digerir, porque todos estos planes cambian de un a\u00f1o para otro. As\u00ed que tenemos que estar al tanto exactamente de lo que has dicho. Lo mejor es ponerse en contacto con un agente, sobre todo de ICCU Insurance Services, para obtener la experiencia y los conocimientos necesarios para asegurarte de que no vas por mal camino y de que consigues el plan con el que puedes trabajar el resto del a\u00f1o.   <\/mark><\/p>\n\n<p>S\u00ed. De acuerdo. No quer\u00eda detenerte ah\u00ed, pero ahora estamos en Medicare D, que es la cobertura de medicamentos con receta, \u00bfverdad?<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed. La Parte D es la m\u00e1s f\u00e1cil de asociar con los medicamentos recetados. As\u00ed que es una cosa que, vas a querer tener, hay ventanas de inscripci\u00f3n tard\u00eda o sanciones que, que pueden ocurrir. Sobre todo con la parte B y la parte D.  <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">As\u00ed que si no te inscribes en un plan de la Parte B o de la Parte D, cuando tengas 65 a\u00f1os y cumplas los requisitos por primera vez, existe la posibilidad de que te impongan una penalizaci\u00f3n por inscripci\u00f3n tard\u00eda m\u00e1s adelante. Por tanto, independientemente de si tomas medicamentos con receta o no, cuando cumplas 65 a\u00f1os y te inscribas en Medicare, querr\u00e1s asegurarte de que tienes un plan de medicamentos con receta de la Parte D. <\/mark><\/p>\n\n<p>S\u00ed, ese es el momento. \u00c9se es el momento. \u00c9sas son las cosas clave que creo que un experto puede ayudar realmente a guiarte. As\u00ed que te agradezco que est\u00e9s aqu\u00ed para nuestros miembros. Es realmente impresionante porque puede ser un poco, puede ser un poco complicado. \u00bfHas tenido alguna historia de \u00e9xito con alg\u00fan miembro que te gustar\u00eda compartir? S\u00e9 que ya hemos hablado de una, pero creo que ser\u00eda genial que nuestros espectadores la vieran o escucharan.      <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed, una de mis historias favoritas, fue la \u00faltima ventana de inscripci\u00f3n o el \u00faltimo periodo de inscripci\u00f3n del 15 de Octubre al 7 de Diciembre. Ten\u00edamos a un se\u00f1or que estaba inscrito en un plan que exist\u00eda desde hac\u00eda a\u00f1os, y el a\u00f1o pasado este plan abandonaba el condado en el que viv\u00eda. <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">As\u00ed que cuando me reun\u00ed con \u00e9l estaba bastante desanimado, llevaba 10 a\u00f1os con este plan. No sab\u00eda realmente si hab\u00eda algo m\u00e1s ah\u00ed fuera. Ten\u00eda muchas complicaciones de salud, tomaba muchas recetas, as\u00ed que se sent\u00eda c\u00f3modo con el plan que ten\u00eda porque sab\u00eda lo que cubr\u00eda y para qu\u00e9 pod\u00eda utilizarlo.  <\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">As\u00ed que cuando me reun\u00ed con \u00e9l, estaba decidido a que no iba a haber un plan que se adaptara a \u00e9l tan bien como el otro plan.<\/mark><\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Pero despu\u00e9s de actuar con la debida diligencia y ver cu\u00e1les eran sus necesidades, pudimos encontrarle un plan a\u00fan mejor, que le ahorraba mucho dinero. Hab\u00eda un plan que ten\u00eda una prima de $0. Ya pagaba una prima de cien d\u00f3lares al mes por el plan que ten\u00eda, pero pudimos ahorrarle cien d\u00f3lares al mes, y de todas las recetas que tomaba, le ahorramos m\u00e1s de dos mil d\u00f3lares en todo el a\u00f1o.  <\/mark><\/p>\n\n<p>Dios m\u00edo, eso es muy importante.<\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">S\u00ed, fue, fue una gran diferencia. Y s\u00f3lo ver el suspiro de alivio en su cara cuando dice: \u00abNo cre\u00eda que hubiera nada mejor que lo que ten\u00eda\u00bb. Y todo forma parte de lo que hacemos aqu\u00ed con ICCU en general. Velamos por sus intereses. No intentamos obligarles a nada que no tenga sentido. Pudimos encontrarles una soluci\u00f3n mejor.     <\/mark><\/p>\n\n<p>Muchas gracias por compartirlo. Creo que es fant\u00e1stico. Y realmente habla de lo que siempre hacemos en ICCU. Y es encontrar formas de ayudar a nuestros miembros a alcanzar el \u00e9xito financiero. Y eso puede ser con sus productos y servicios financieros tradicionales, pero tambi\u00e9n puede ser con nuestros servicios de seguros. As\u00ed que creo que eso es, eso es realmente impresionante.     <\/p>\n\n<p><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-green-color\">Gracias.<\/mark><\/p>\n\n<p>Bueno, muchas gracias por estar aqu\u00ed. Ha sido un placer hablar contigo. Nuestro equipo de servicios de seguros est\u00e1 aqu\u00ed para guiarte en este proceso y responder a cualquier pregunta que puedas tener. No olvides suscribirte a nuestro canal para recibir notificaciones de futuros episodios y nos vemos la pr\u00f3xima vez.   <\/p>\n\n<p class=\"has-md-font-size\"><em>*No ofrecemos todos los planes disponibles en tu zona. La informaci\u00f3n que proporcionemos se limitar\u00e1 a los planes que ofrezcamos en tu zona. Ponte en contacto con medicare.gov o 1-800-MEDICARE para informarte de todas tus opciones. No hay obligaci\u00f3n de inscribirse para recibir nuestros servicios. No est\u00e1 avalado ni afiliado a Medicare. ICCU Insurance Services, LLC es una filial propiedad de ICCU y una agencia de seguros autorizada. Los negocios realizados con ICCU Insurance Services, LLC son separados y distintos de cualquier negocio realizado con ICCU. Los productos de seguros no son productos ni obligaciones de ICCU. Los productos de seguros no son productos ni obligaciones de ICCU, no est\u00e1n asegurados por la NCUA ni por el gobierno federal, no est\u00e1n avalados ni garantizados por ICCU ni por ninguna agencia gubernamental y pueden perder valor.   <\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Aprender los entresijos de Medicare puede parecerse mucho a aprender una lengua extranjera. Al principio puede parecer un galimat\u00edas complicado, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":19604,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_searchwp_excluded":"","footnotes":""},"categories":[549],"tags":[577,578,579,580,581],"class_list":["post-19606","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financial-education","tag-medicare-es","tag-seguro","tag-medigap-es","tag-servicios-de-seguros","tag-equipo-de-seguros"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.9 (Yoast SEO v28.0) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Los ABCD de Medicare con el agente de seguros Corban Latimore - ICCU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los ABCD de Medicare con el agente de seguros Corban Latimore\" \/>\n<meta property=\"og:description\" content=\"Aprender los entresijos de Medicare puede parecerse mucho a aprender una lengua extranjera. Al principio puede parecer un galimat\u00edas complicado, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/\" \/>\n<meta property=\"og:site_name\" content=\"ICCU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/IdahoCentralCreditUnion\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/IdahoCentralCreditUnion\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-17T16:23:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-16T18:37:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"530\" \/>\n\t<meta property=\"og:image:height\" content=\"380\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"ICCU\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Idaho_Central\" \/>\n<meta name=\"twitter:site\" content=\"@Idaho_Central\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"ICCU\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"18 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/\"},\"author\":{\"name\":\"ICCU\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#\\\/schema\\\/person\\\/dd9140c89706c5ddd694ffbe26867e8e\"},\"headline\":\"Los ABCD de Medicare con el agente de seguros Corban Latimore\",\"datePublished\":\"2024-10-17T16:23:01+00:00\",\"dateModified\":\"2025-04-16T18:37:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/\"},\"wordCount\":3521,\"publisher\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Blog-featured-image-medicare-transcript.webp\",\"keywords\":[\"medicare\",\"seguro\",\"medigap\",\"servicios de seguros\",\"equipo de seguros\"],\"articleSection\":[\"Educaci\u00f3n financiera\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/\",\"url\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/\",\"name\":\"Los ABCD de Medicare con el agente de seguros Corban Latimore - ICCU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Blog-featured-image-medicare-transcript.webp\",\"datePublished\":\"2024-10-17T16:23:01+00:00\",\"dateModified\":\"2025-04-16T18:37:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Blog-featured-image-medicare-transcript.webp\",\"contentUrl\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Blog-featured-image-medicare-transcript.webp\",\"width\":530,\"height\":380,\"caption\":\"A flat design of different Medicare and insurance-related objects, like first aid, hearts, and pills.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/blog\\\/financial-education\\\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los ABCD de Medicare con el agente de seguros Corban Latimore\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/\",\"name\":\"ICCU\",\"description\":\"Looking after your daily balance.\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#organization\"},\"alternateName\":\"ICCU\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#organization\",\"name\":\"ICCU\",\"url\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ICCU-logo-2color_696x696.png\",\"contentUrl\":\"https:\\\/\\\/www.iccu.com\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/ICCU-logo-2color_696x696.png\",\"width\":696,\"height\":696,\"caption\":\"ICCU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/IdahoCentralCreditUnion\",\"https:\\\/\\\/x.com\\\/Idaho_Central\",\"https:\\\/\\\/www.youtube.com\\\/idahocentralcu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idahocentralcreditunion\\\/\",\"https:\\\/\\\/www.instagram.com\\\/idahocentralcu\\\/\"],\"description\":\"ICCU is a state-chartered credit union in the western United States, headquartered in Chubbuck, Idaho. Whether you\u2019re banking in the branch or banking on the go, ICCU is looking after your daily balance. Get great rates on auto and home loans. Check out our Visa Rewards Cards. Discover more perks with Central Plus Checking. Bank your way with drive-thru, ATM, live video chat, mobile banking. Open Saturdays. We also offer investment, insurance, and business solutions. As a member of ICCU, you\u2019ll have a financial leader that\u2019s helping you achieve financial success. Routing Number: 324173626. NMLS ID: 433926.\",\"email\":\"memberservice@iccu.com\",\"telephone\":\"(800) 456-5067\",\"foundingDate\":\"1940-06-28\",\"taxID\":\"82-0217065\",\"duns\":\"108135278\",\"numberOfEmployees\":{\"@type\":\"QuantitativeValue\",\"minValue\":\"1001\",\"maxValue\":\"5000\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.iccu.com\\\/es\\\/#\\\/schema\\\/person\\\/dd9140c89706c5ddd694ffbe26867e8e\",\"name\":\"ICCU\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g\",\"caption\":\"ICCU\"},\"description\":\"ICCU is the premier lender and credit union in Idaho, Washington, Oregon, and Arizona. Whether you\u2019re banking in the branch or banking on the go, ICCU is looking after your daily balance. Get great rates on auto and home loans. Check out our Visa Rewards Cards. Discover more perks with Central Plus Checking. Bank your way with drive-thru, ATM, live video chat, mobile banking. Open Saturdays. We also offer investment, insurance, and business solutions. As a member of ICCU, you\u2019ll have a financial leader that\u2019s helping you achieve financial success.\",\"sameAs\":[\"https:\\\/\\\/www.iccu.com\",\"https:\\\/\\\/www.facebook.com\\\/IdahoCentralCreditUnion\",\"http:\\\/\\\/instagram.com\\\/idahocentralcu\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/idahocentralcreditunion\",\"https:\\\/\\\/x.com\\\/Idaho_Central\",\"https:\\\/\\\/www.youtube.com\\\/idahocentralcu\",\"https:\\\/\\\/en.wikipedia.org\\\/wiki\\\/Idaho_Central_Credit_Union\"],\"birthDate\":\"1940-06-28\",\"knowsLanguage\":[\"English\",\"Spanish\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Los ABCD de Medicare con el agente de seguros Corban Latimore - ICCU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/","og_locale":"es_ES","og_type":"article","og_title":"Los ABCD de Medicare con el agente de seguros Corban Latimore","og_description":"Aprender los entresijos de Medicare puede parecerse mucho a aprender una lengua extranjera. Al principio puede parecer un galimat\u00edas complicado, [&hellip;]","og_url":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/","og_site_name":"ICCU","article_publisher":"https:\/\/www.facebook.com\/IdahoCentralCreditUnion","article_author":"https:\/\/www.facebook.com\/IdahoCentralCreditUnion","article_published_time":"2024-10-17T16:23:01+00:00","article_modified_time":"2025-04-16T18:37:45+00:00","og_image":[{"width":530,"height":380,"url":"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp","type":"image\/webp"}],"author":"ICCU","twitter_card":"summary_large_image","twitter_creator":"@Idaho_Central","twitter_site":"@Idaho_Central","twitter_misc":{"Escrito por":"ICCU","Tiempo de lectura":"18 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#article","isPartOf":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/"},"author":{"name":"ICCU","@id":"https:\/\/www.iccu.com\/es\/#\/schema\/person\/dd9140c89706c5ddd694ffbe26867e8e"},"headline":"Los ABCD de Medicare con el agente de seguros Corban Latimore","datePublished":"2024-10-17T16:23:01+00:00","dateModified":"2025-04-16T18:37:45+00:00","mainEntityOfPage":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/"},"wordCount":3521,"publisher":{"@id":"https:\/\/www.iccu.com\/es\/#organization"},"image":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp","keywords":["medicare","seguro","medigap","servicios de seguros","equipo de seguros"],"articleSection":["Educaci\u00f3n financiera"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/","url":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/","name":"Los ABCD de Medicare con el agente de seguros Corban Latimore - ICCU","isPartOf":{"@id":"https:\/\/www.iccu.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#primaryimage"},"image":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#primaryimage"},"thumbnailUrl":"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp","datePublished":"2024-10-17T16:23:01+00:00","dateModified":"2025-04-16T18:37:45+00:00","breadcrumb":{"@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#primaryimage","url":"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp","contentUrl":"https:\/\/www.iccu.com\/wp-content\/uploads\/2024\/10\/Blog-featured-image-medicare-transcript.webp","width":530,"height":380,"caption":"A flat design of different Medicare and insurance-related objects, like first aid, hearts, and pills."},{"@type":"BreadcrumbList","@id":"https:\/\/www.iccu.com\/es\/blog\/financial-education\/the-abcds-of-medicare-with-insurance-agent-corban-latimore\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.iccu.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los ABCD de Medicare con el agente de seguros Corban Latimore"}]},{"@type":"WebSite","@id":"https:\/\/www.iccu.com\/es\/#website","url":"https:\/\/www.iccu.com\/es\/","name":"ICCU","description":"Looking after your daily balance.","publisher":{"@id":"https:\/\/www.iccu.com\/es\/#organization"},"alternateName":"ICCU","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.iccu.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.iccu.com\/es\/#organization","name":"ICCU","url":"https:\/\/www.iccu.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.iccu.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.iccu.com\/wp-content\/uploads\/2025\/03\/ICCU-logo-2color_696x696.png","contentUrl":"https:\/\/www.iccu.com\/wp-content\/uploads\/2025\/03\/ICCU-logo-2color_696x696.png","width":696,"height":696,"caption":"ICCU"},"image":{"@id":"https:\/\/www.iccu.com\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/IdahoCentralCreditUnion","https:\/\/x.com\/Idaho_Central","https:\/\/www.youtube.com\/idahocentralcu","https:\/\/www.linkedin.com\/company\/idahocentralcreditunion\/","https:\/\/www.instagram.com\/idahocentralcu\/"],"description":"ICCU is a state-chartered credit union in the western United States, headquartered in Chubbuck, Idaho. Whether you\u2019re banking in the branch or banking on the go, ICCU is looking after your daily balance. Get great rates on auto and home loans. Check out our Visa Rewards Cards. Discover more perks with Central Plus Checking. Bank your way with drive-thru, ATM, live video chat, mobile banking. Open Saturdays. We also offer investment, insurance, and business solutions. As a member of ICCU, you\u2019ll have a financial leader that\u2019s helping you achieve financial success. Routing Number: 324173626. NMLS ID: 433926.","email":"memberservice@iccu.com","telephone":"(800) 456-5067","foundingDate":"1940-06-28","taxID":"82-0217065","duns":"108135278","numberOfEmployees":{"@type":"QuantitativeValue","minValue":"1001","maxValue":"5000"}},{"@type":"Person","@id":"https:\/\/www.iccu.com\/es\/#\/schema\/person\/dd9140c89706c5ddd694ffbe26867e8e","name":"ICCU","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d8ee624d640de70ddacaf84d04ec8c852253137918fdfe41377eab4253c7af47?s=96&d=mm&r=g","caption":"ICCU"},"description":"ICCU is the premier lender and credit union in Idaho, Washington, Oregon, and Arizona. Whether you\u2019re banking in the branch or banking on the go, ICCU is looking after your daily balance. Get great rates on auto and home loans. Check out our Visa Rewards Cards. Discover more perks with Central Plus Checking. Bank your way with drive-thru, ATM, live video chat, mobile banking. Open Saturdays. We also offer investment, insurance, and business solutions. As a member of ICCU, you\u2019ll have a financial leader that\u2019s helping you achieve financial success.","sameAs":["https:\/\/www.iccu.com","https:\/\/www.facebook.com\/IdahoCentralCreditUnion","http:\/\/instagram.com\/idahocentralcu","https:\/\/www.linkedin.com\/company\/idahocentralcreditunion","https:\/\/x.com\/Idaho_Central","https:\/\/www.youtube.com\/idahocentralcu","https:\/\/en.wikipedia.org\/wiki\/Idaho_Central_Credit_Union"],"birthDate":"1940-06-28","knowsLanguage":["English","Spanish"]}]}},"_links":{"self":[{"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/posts\/19606","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/comments?post=19606"}],"version-history":[{"count":2,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/posts\/19606\/revisions"}],"predecessor-version":[{"id":22081,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/posts\/19606\/revisions\/22081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/media\/19604"}],"wp:attachment":[{"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/media?parent=19606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/categories?post=19606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.iccu.com\/es\/wp-json\/wp\/v2\/tags?post=19606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}